{"id":2842,"date":"2017-06-18T16:40:07","date_gmt":"2017-06-18T14:40:07","guid":{"rendered":"http:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842"},"modified":"2018-06-11T14:58:05","modified_gmt":"2018-06-11T12:58:05","slug":"der-inhalt-der-antisemitismus-doku-juden-hass-den-arte-wdr-nicht-zeigen-wollen-der-aber-am-13-06-2017-bei-bild-online-zu-sehen-war","status":"publish","type":"post","link":"https:\/\/rettung-fuer-deutschland.de\/blog\/der-inhalt-der-antisemitismus-doku-juden-hass-den-arte-wdr-nicht-zeigen-wollen-der-aber-am-13-06-2017-bei-bild-online-zu-sehen-war\/","title":{"rendered":"Der Inhalt der Antisemitismus-DOKU JUDEN-HASS, den ARTE &#038; WDR nicht zeigen wollen, der aber am 13.06.2017 bei BILD online zu sehen war!"},"content":{"rendered":"<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-01-text-620x349.jpg\" width=\"620\" height=\"349\" class=\"alignnone size-medium\" \/><\/a><\/p>\n<p><strong>BDS ist Boycott, Divestment and Sanctions (dt. Boykott, Kapitalabzug und Sanktionen, kurz BDS)<\/strong> ist eine umfassende internationale politische Kampagne gegen Israel, die am 9. Juli 2005 auf den Aufruf von \u00fcber 170 pal\u00e4stinensischen Nicht-Regierungsorganisationen hin ins Leben gerufen wurde. Die Kampagne erregte internationales Aufsehen und hat prominente Bef\u00fcrworter, aber auch viele Kritiker. Letztere sehen im Auftreten und Agieren der Organisation den Versuch einer Delegitimierung Israels. GOTTES Zusage &#038; Verhei\u00dfung f\u00fcr sein Volk der Juden mit dem Staat Israel, Bibel, AT, Sacharja 12,9-10: Und zu der Zeit werde ich darauf bedacht sein, alle Heiden zu vertilgen, die gegen Jerusalem (Israel und alle Juden) gezogen sind. Aber \u00fcber das Haus David (alle Juden und Israel) und \u00fcber die B\u00fcrger Jerusalems will ich ausgie\u00dfen den Geist der Gnade und des Gebets (Heiliger Geist).<\/p>\n<h1><strong>JUDEN-HASS &#8211; die Doku, die ARTE &#038; WDR nicht zeigen wollen!<\/strong><\/h1>\n<p><strong>Die TV-Dokumentation belegt in Europa grassierenden, teils hoff\u00e4higen Judenhass, f\u00fcr den es nur zwei Worte gibt: ekelhaft und besch\u00e4mend.<\/strong><\/p>\n<p>Seit Wochen wird bis in die h\u00f6chsten Ebenen der Politik \u00fcber diese \u2013 von Geb\u00fchrengeldern produzierte \u2013 Dokumentation diskutiert. Ohne dass die B\u00fcrger sie sehen d\u00fcrfen. Ohne dass sie sich ein Urteil bilden k\u00f6nnen.<\/p>\n<p>Der Verdacht liegt bitter nah, dass diese Dokumentation nicht gezeigt wird, weil sie politisch nicht genehm ist, weil sie ein antisemitisches Weltbild in weiten Teilen der Gesellschaft belegt, das ersch\u00fctternd ist.<\/p>\n<p><strong>Deutschland ist ganz sicher nicht das Land, in dem antisemitische Vorurteile besch\u00f6nigt, verschwiegen, \u00fcbert\u00fcncht werden sollten.<\/strong><br \/>\nUnsere historische Verantwortung verpflichtet uns, den Uns\u00e4glichkeiten entschlossen entgegenzutreten, die diese Dokumentation belegt. Dazu m\u00fcssen alle wissen, womit wir es zu tun haben. Deswegen zeigte BILD f\u00fcr 24 Stunden online am 13.06.2017, redaktionell eingeordnet und eingebettet, was im TV nicht gezeigt werden sollte.<\/p>\n<h2><strong>Der Kampf gegen Antisemitismus ist in Deutschland ein \u00fcberragendes Interesse. Das sagen Experten und Betroffene<\/strong><\/h2>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-0-michael-wolffsohn-150x168.jpg\" width=\"150\" height=\"168\" class=\"alignleft size-medium\" \/><\/a><strong>Prof. Michael Wolffsohn, Historiker<\/strong><br \/>\n\u201eGl\u00fcckwunsch! Das ist die mit Abstand beste und kl\u00fcgste und historisch tiefste, zugleich leider hochaktuelle und wahre Doku zu diesem Thema.\u201c<\/p>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-0-goetz-ali-150x184.jpg\" width=\"150\" height=\"184\" class=\"alignright size-medium\" \/><\/a><strong>G\u00f6tz Aly, Historiker und Publizist<\/strong><br \/>\n\u201eDer Film dokumentiert die korrupte, Hamas gesteuerte Selbstverwaltung von Uno-Hilfsgeldern in Gaza. Nun behauptet Arte-Programmdirektor Le Diberder, dem Film mangele es an &#8222;Multiperspektivit\u00e4t&#8220; Das Gegenteil ist richtig.\u201c<\/p>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-0-ahmand-monsour-150x168.jpg\" width=\"150\" height=\"168\" class=\"alignleft size-medium\" \/><\/a><strong>Ahmad Mansour, Nahost-Experte und Publizist<\/strong><br \/>\n\u201eInhaltlich ist der Film gro\u00dfartig und u\u0308berfa\u0308llig&#8230; Ich finde es merkwu\u0308rdig, dass ausgerechnet ein renommierter o\u0308ffentlich-rechtlicher Sender wie ARTE Probleme mit der Realita\u0308t hat.\u201c<\/p>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-0-mathias-kuentzel-150x175.jpg\" width=\"150\" height=\"175\" class=\"alignright size-medium\" \/><\/a><strong>Matthias K\u00fcntzel, Politikwissenschaftler und Antisemitimus-Forscher&#8230;<\/strong><br \/>\n&#8230; lobt, dass der Film \u201ewissenschaftlich fundiert\u201c \u00fcber \u201eneue Auswirkungen des Antisemitismus vermittelt\u201c. Dabei sei ihm bewusst, \u201edass \u00fcber den Nahostkonflikt unter franz\u00f6sischen Intellektuellen anders gesprochen wird als unter deutschen; die Abneigung gegen Israel scheint in Frankreich zuweilen st\u00e4rker.\u201c<\/p>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-0-alain-le-deberder-150x173.jpg\" width=\"150\" height=\"173\" class=\"alignleft size-medium\" \/><\/a><strong>Arte-Programmdirektor Alain Le Diberder<\/strong><br \/>\n\u201eDie gelieferte Sendung konzentriert sich (\u2026) haupts\u00e4chlich auf den Nahen Osten. Damit entsprach sie nicht dem von der Programmkonferenz formulierten Auftrag, sodass sie nicht akzeptiert werden konnte. Dieser Standpunkt enth\u00e4lt keine Wertung \u00fcber die Qualit\u00e4t des Films oder \u00fcber die darin vertretenen Thesen.\u201c Zudem mangele es an \u201eAusgewogenheit\u201c.<\/p>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-0-wdr-150x45.jpg\" width=\"150\" height=\"45\" class=\"alignright size-medium\" \/><\/a><strong>WDR<\/strong><br \/>\nDer WDR lie\u00df mitteilen, man habe den Film \u201enach der Ablehnung durch ARTE einer erneuten Sichtung unterzogen und handwerkliche Bedenken. Wir pr\u00fcfen derzeit intensiv, ob die Dokumentation den journalistischen Standards und Programmgrunds\u00e4tzen des WDR entspricht (\u2026) Wir bedauern, dass die redaktionelle Abnahme im WDR offenbar nicht den \u00fcblichen in unserem Haus geltenden Standards gen\u00fcgte. Wir arbeiten das derzeit intern auf. Dabei geht uns Sorgfalt vor Schnelligkeit \u2013 ungeachtet der aktuellen \u00f6ffentlichen Diskussion \u00fcber einen nicht ausgestrahlten Film.\u201c<\/p>\n<h2><strong>AUSZ\u00dcGE AUS DER ARTE-DOKU:<\/strong><\/h2>\n<h2><strong>Antisemitismus im Europaparlament<\/strong><\/h2>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-02-abbas-620x368.jpg\" width=\"620\" height=\"386\" class=\"alignnone size-medium\" \/><\/a><\/p>\n<p>Ein Auszug aus der Doku: 23. Juni 2016, Pal\u00e4stinenser-Pr\u00e4sident Mahmud Abbas im EU-Parlament. Er behauptet: \u201eVor nur einer Woche haben Rabbiner in Israel ihre Regierung aufgefordert, unser Wasser zu vergiften, um Pal\u00e4stinenser zu t\u00f6ten.\u201c Das sei \u201eAnstiftung zum Massenmord\u201c.<\/p>\n<p><strong>Martin Schulz (SPD), damals Parlaments-Pr\u00e4sident, twitterte: \u201eEine inspirierende Rede.\u201c Nach Protesten zog Abbas die infame Falsch-Behauptung zur\u00fcck: Er sei \u201efalsch informiert\u201c worden. Die Menschenrechtsbeauftragte der Linkspartei, Annette Groth, warnt im Film dennoch vor \u201eden ganzen Chemikalien, Tonnen, Tonnen\u201c, mit denen \u201edie Wasserversorgung in Gaza kaputt gemacht\u201c werde. Das sei \u201ehoch gef\u00e4hrlich, f\u00fcr alle\u201c. Auch f\u00fcr diese Behauptung gibt es keinen Beleg.<\/strong><\/p>\n<h2><strong>Antisemitismus in Paris<\/strong><\/h2>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-03-paris-620x349.jpg\" width=\"620\" height=\"349\" class=\"alignnone size-medium\" \/><\/a><\/p>\n<p>Die Macher der Doku waren auch in der Pariser Vorstadt Sarcelles unterwegs. 13 000 Juden leben hier mit Christen und Muslimen.<\/p>\n<p><strong>Algerier verbreiteten hier im Sommer 2014 einen Aufruf: \u201ePAL\u00c4STINA, kommt ausger\u00fcstet mit M\u00f6rsern, Feuerl\u00f6schern, Kn\u00fcppeln. Wir nehmen uns das Judenviertel vor.\u201c 3000 Demonstranten stecken eine Synagoge in Brand, schreien \u201eTod den Juden\u201c.<\/strong><\/p>\n<p>Seitdem leben jugendliche Juden in Sarcelles in Angst: \u201eWenn wir in die anderen Viertel gehen, riskieren wir unser Leben.\u201c Immer mehr Familien wandern nach Israel aus, berichtet der B\u00fcrgermeister: \u201eWas f\u00fcr ein Versagen von Republik und Land!\u201c<\/p>\n<h2><strong>Antisemitismus in Berlin, Frankfurt, Essen<\/strong><\/h2>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-04-demo-deutschland-620x349.jpg\" width=\"620\" height=\"349\" class=\"alignnone size-medium\" \/><\/a><\/p>\n<p>Ersch\u00fctternder Teil der Doku aus dem Juli 2014: W\u00e4hrend des Gaza-Kriegs demonstrieren Tausende in Berlin, Frankfurt, Essen, skandieren Hass-Parolen gegen Israel: \u201eTod den Juden\u201c, \u201eTod Israel\u201c, \u201eAdolf Hitler, Adolf Hitler\u201c und \u201eJude, Jude, feiges Schwein, komm heraus und k\u00e4mpf allein\u201c.<\/p>\n<p><strong>Der Beobachter einer \u00e4hnlichen Anti-Israel-Demo in Paris wundert sich: \u201eKeiner reagiert darauf, keiner. Da sind 800 Leute, die sich das in Ruhe anh\u00f6ren; keiner verlangt, dass der Redner aufh\u00f6rt, keiner ruft dazwischen oder protestiert.\u201c<\/strong><\/p>\n<h2><strong>Antisemitismus im Kinder-Fernsehen in Hamas-TV<\/strong><\/h2>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-05-hamas-tv-620x366.jpg\" width=\"620\" height=\"366\" class=\"alignnone size-medium\" \/><\/a><\/p>\n<p>Auszug aus der Doku: Im \u201eHamas-TV\u201c, dem offiziellen Fernsehkanal in Gaza, treten im September 2015 zwei niedliche Kinder in Milit\u00e4runiform auf. Auf die Frage, was ihr Berufswunsch sei, antwortete der eine: \u201eMitglied der Al-Quassam-Brigaden\u201c (Terrorarmee der Hamas). Sein Freund antwortet: \u201eIngenieur, damit ich Juden in die Luft jagen kann.\u201c<\/p>\n<p><strong>Die TV-Doku f\u00fcr arte zeigt auch Hass-Propaganda muslimischer Geistlicher und Politiker, die davon tr\u00e4umen, Israel zu bestrafen und auszul\u00f6schen.<\/strong><\/p>\n<h2><strong>Antisemitismus unter Rappern<\/strong><\/h2>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-06-rapper-hass-620x358.jpg\" width=\"620\" height=\"358\" class=\"alignnone size-medium\" \/><\/a><\/p>\n<p>Noch ein Auszug: Boykott-Kampagnen gegen Israel werden unterst\u00fctzt von Rappern wie der Gruppe \u201eKaveh, Quazid &#038; Erko\u201c.<\/p>\n<p><strong>Sie behaupten: \u201eIsrael verursacht einen Genozid in Gaza\u201c. Es sei \u201eder Kampf David gegen Goliath, Kolonie gegen die Atommacht. Boykottiere Israel, ist unsere Botschaft.\u201c<\/strong><\/p>\n<p>Die Doku zeigt auch Ex-Pink-Floyd-Rocker Roger Waters, der den Boykott unterst\u00fctzt und Auftritte in Israel verweigert. Sein Motto: \u201eK\u00fcnstler erheben ihre Stimme.\u201c<\/p>\n<h2><strong>Antisemitismus unter Journalisten<\/strong><\/h2>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-07-ken-jespen-620x340.jpg\" width=\"620\" height=\"340\" class=\"alignnone size-medium\" \/><\/a><\/p>\n<p>Die Doku zeigt den Ex-Linken J\u00fcrgen Els\u00e4sser, inzwischen Chefredakteur des rechtspopulistischen Magazins \u201eCompact\u201c, auf einer Demo vor dem Berliner Hauptbahnhof (Mai 2015): \u201eWir m\u00fcssen uns wehren, sowohl gegen die Islamisierung als auch die Israelisierung\u201c, erkl\u00e4rt er in seiner Rede.<\/p>\n<p><strong>Ein Zuh\u00f6rer sagt: \u201eZionismus ist f\u00fcr mich Mafia\u201c, eine \u201eGeld-Mafia\u201c, die \u201emit der Zerst\u00f6rung der Menschheit verdient\u201c. Ken Jebsen, ehemals Moderator beim ARD-Radio \u201eFritz\u201c erkl\u00e4rt im Netz: \u201eDas geheime Hobby dieser Zio-Cons ist die Schaffung eines israelischen Gro\u00dfreichs.\u201c<\/strong><\/p>\n<h2><strong>Die Rolle von Hilfsorganisationen<\/strong><\/h2>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-08-unrw-gaza-620x358.jpg\" width=\"620\" height=\"358\" class=\"alignnone size-medium\" \/><\/a><\/p>\n<p>Die Doku \u00fcbt auch Kritik an internationalen Organisationen. Manche unterst\u00fctzten umstrittene Projekte in Israel und den besetzten Gebieten. So habe z. B. \u201eBrot f\u00fcr die Welt\u201c von 2013 bis 2015 rund 800 000 Euro an B\u2018Tselem gezahlt. Der Verein, den Au\u00dfenminister Sigmar Gabriel (SPD) bei seiner Israel-Reise besuchte, wirft Israels Regierung Apartheid und Nazi-Methoden vor.<\/p>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-09-brot-welt-150x78.jpg\" width=\"150\" height=\"78\" class=\"alignright size-medium\" \/><\/a><strong>Die Doku-Autoren hatten \u201eBrot f\u00fcr die Welt\u201c nicht befragt, was der WDR beanstandet. Auf BILD-Anfrage bestreitet das Kirchen-Hilfswerk die Zahlung nicht, erkl\u00e4rt jedoch: B\u2018Tselem beteilige sich \u201enicht an Kampagnen und Aufrufen gegen Israel\u201c, sondern k\u00e4mpfe \u201ef\u00fcr die Einhaltung der Menschenrechte\u201c.<\/strong><\/p>\n<p>Das katholische Hilfswerk \u201eMisereor\u201c zahlt keine Hilfen an B\u2018Tselem, was in der Doku missverst\u00e4ndlich formuliert ist.<\/p>\n<h2><strong>DIE DOKU<\/strong><\/h2>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-antisemitismus-doku-10-kinder-tv-hamas-video-210x142.jpg\" width=\"210\" height=\"142\" class=\"alignright size-medium\" \/><\/a><strong>HETZE, HASS UND HAMAS Wovon handelt die TV-Doku?<\/strong><br \/>\nDer von ARTE beim WDR in Auftrag gegebene 90-Minuten-Film berichtet \u00fcber den seit Jahren anwachsenden Juden-Hass. Film-Autor Joachim Schr\u00f6der zu BILD: \u201eDie Recherchen zum Film sind wasserdicht. Notfalls werden wir Formulierungen pr\u00e4zisieren.\u201c<\/p>\n<p><strong>Die Autoren besuchten auch das UN-Fl\u00fcchtlingswerk f\u00fcr die Pal\u00e4stinenser (UNRWA).<br \/>\nFrage: Wo versickern 1,36 Milliarden Euro Jahresbudget, w\u00e4hrend Schulen und Krankenh\u00e4user in Gaza vor sich hingammeln? Sprecher Adnan Abu Hasna: Man habe \u201eController\u201c und \u201eBuchpr\u00fcfer\u201c, sei \u201ein st\u00e4ndigem Kontakt\u201c mit EU und UN. Ein Student der Uni in Gaza wird konkreter: \u201eDass es hier Korruption gibt, l\u00e4sst sich nicht abstreiten.\u201c<\/strong><\/p>\n<p>Quelle: Bild.de &#8211; online 13.06.2017<\/p>\n<p>Autor Uwe Melzer:<br \/>\n<strong>Diese Dokumentation \u201eAuserw\u00e4hlt und ausgegrenzt Der Hass auf Juden in Europa\u201c wurde im Internet zensiert (bzw. Rechteverletzung). Die beiden folgenden Video-Links bei Youtube mussten vom Netz genommen werden:<\/strong><br \/>\n<strong><a href=\"https:\/\/www.youtube.com\/watch?v=rRLSnDkNm74\"><font color=\"#000080\">https:\/\/www.youtube.com\/watch?v=rRLSnDkNm74<\/font><\/a><\/strong><br \/>\n<strong><a href=\"https:\/\/www.youtube.com\/watch?v=mEQ5MNGz2I4\"><font color=\"#000080\">https:\/\/www.youtube.com\/watch?v=mEQ5MNGz2I4<\/font><\/a><\/strong><\/p>\n<p><strong>Dazu passt auch dieser Presseartikel:<br \/>\n<a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2817\"><font color=\"#000080\">Die Fakten aus der Antisemitismus-Doku m\u00fcssen ans Licht &#8211; FILM ZU ISRAEL-HASS!<\/font><\/a><\/strong><\/p>\n<p><strong><em><font color=\"#d63c42\">Bei der gesamten Diskussion sollte als Grundlage dienen, dass der gesamte christliche Glaube, das gesamte Christentum, egal ob evangelische Kirche, katholische Kirche, orthodoxe Kirche oder Freikirchen und christliche Gemeinden weltweit auf dem biblischen, g\u00f6ttlichen und j\u00fcdischen Fundament der Geschichte von Israel und Jerusalem aufgebaut ist. Die christliche Bibel und die j\u00fcdische Thora umfassen und dokumentieren insgesamt ca. 6.000 Jahre Menschheitsgeschichte mit einem ungeteilten Jerusalem als Hauptstadt der Juden und dem Staat Israel. Besonders wir in Deutschland, die ein halbes Jahrhundert unter der Trennung in Berlin gelitten haben, sollten nicht von den Israeliten fordern, dass Jerusalem geteilt wird. GOTT selbst sagt in der Bibel, dass Israel und die Juden von ihm beh\u00fctet und bewacht werden, wie sein eigener Augapfel. Aus biblischer Sicht gilt daher auch, wer Israel oder die Juden angreift, greift direkt GOTT an. Und das wird nie gut ausgehen und zwar f\u00fcr die Angreifer. GOTT wird nicht mehr zulassen, dass Israel &#038; Jerusalem vernichtet wird und nicht in der Hand der Juden bleibt, bis auf die letzten 3 Tage bevor Jesus Christus wieder auf diese Erde kommt und zwar exakt in Jerusalem durch das Ost-TOR. Gleichzeitig werden dann alle Feinde und Armeen vernichtet, die 3 Tage lang Krieg in Israel und Jerusalem gef\u00fchrt haben. Mit solch einem GOTT w\u00fcrde ich mich pers\u00f6nlich nicht anlegen.<\/font><\/em><\/strong><\/p>\n<p><strong>Vom MINUS zum PLUS! <\/strong><br \/>\n<a href=\"https:\/\/www.minus-plus.de\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ichthys-consulting.de\/foto-vom-minus-zum-plus-250x174.jpg\" width=\"250\" height=\"174\" class=\"alignright\" \/><\/a>Das ist Ihre Chance! Gott sagt, er liebt Sie, er verliert Sie nie aus den Augen. Der Glaube ist da f\u00fcr das Unm\u00f6gliche! Bibel, Neues Testament, Matth\u00e4us 11,5-6 + Lukas 7,22-23: Blinde sehen und Lahme gehen, Auss\u00e4tzige werden rein und Taube h\u00f6ren, Tote stehen auf, und Armen wird das Evangelium gepredigt; und selig ist, wer sich nicht an mir \u00e4rgert. Alle die zu Jesus Christus im neuen Testament der Bibel kamen wurden geheilt. Das ist auch heute noch die Botschaft an die Menschheit. <strong>Am tiefsten Punkt unserer Not setzt das Evangelium von Jesus Christus an. Jesus sah sein Leben als eine Befreiungsaktion. Er sagte, er sei gekommen, \u201czu suchen und zu retten, was verloren ist\u201d.<\/strong> Er selbst hat auch gesagt, dass sein Tod kein Unfall war. Er kam, um zu sterben: \u201cDes Menschen Sohn kam nicht, um sich dienen zu lassen, sondern um zu dienen und sein Leben f\u00fcr viele hinzugeben.\u201d <strong><a href=\"https:\/\/www.minus-plus.de\"><font color=\"#000080\">https:\/\/www.minus-plus.de<\/font><\/a><\/strong><\/p>\n<p><strong>Weitere Presseartikel \u00fcber Israel von Autor Uwe Melzer \/ RfD &#8211; Rettung f\u00fcr Deutschland<\/strong><\/p>\n<p><a href=\" https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2817\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/foto-wp-i-stand-with-israel-blaues-flaggenmeer-junge-dame-620x422.jpg\" width=\"620\" height=\"422\" class=\"alignnone size-medium\" \/><\/a><\/p>\n<p>Wie europ\u00e4ische und amerikanische Steuergelder an pal\u00e4stinensische Terroristen flie\u00dfen! <strong><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=1834\"><font color=\"#000080\">https:\/\/rettung-fuer-deutschland.de\/blog\/?p=1834<\/font><\/a><\/strong><\/p>\n<p>Die israelische Siedlungspolitik im Westjordanland verst\u00f6\u00dft nicht gegen internationales Recht! <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=3353\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=3353<\/font><\/a><\/strong> <\/p>\n<p>Israel &#8211; Besondere Ereignisse &#8211; Mondfinsternis &#8211; Blutmond k\u00fcndigt \u00e4u\u00dferst bedeutendes Ereignis an! <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=3249\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=3249<\/font><\/a><\/strong> <\/p>\n<p>Judenhass &#038; Antisemitismus egal in welcher Einstellung ist ein direkter Angriff gegen GOTT! <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=3229\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=3229<\/font><\/a><\/strong> <\/p>\n<p>Der Atomdeal &#8211; Irans Weihnachten im Juli &#8211; USA und die Welt werden vom Iran get\u00e4uscht! <strong><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=1263\"><font color=\"#000080\">https:\/\/rettung-fuer-deutschland.de\/blog\/?p=1263<\/font><\/a><\/strong> <\/p>\n<p>Die etwas andere Farbenlehre \u00fcber Religionen und Judenhass \/ Blauhass: <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=3193\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=3193<\/font><\/a><\/strong> <\/p>\n<p>Wahlausgang Israel: Sensationell gewinnt Benjamin Netanjahu. Jede Obrigkeit wird von GOTT eingesetzt! <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=2902\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=2902<\/font><\/a><\/strong> <\/p>\n<p>Die Grenzen von Israel mit Jerusalem als Hauptstadt und der Status der Juden als Volk aus GOTTES Sicht! <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=972\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=972<\/font><\/a><\/strong> <\/p>\n<p>GOTT spricht: Wer euch (Israel + Juden) antastet, der tastet meinen Augapfel an. Bibel, AT, Sacharja 2,12: <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=972\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=972<\/font><\/a><\/strong> <\/p>\n<p>Weshalb es keinen Frieden mit Israel und den Arabern gibt! 20 Mythen und Fakten \u00fcber den Nahen Osten. <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=13\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=13<\/font><\/a><\/strong> <\/p>\n<p>Die Wahrheit \u00fcber die Entstehung von Israel und die Fl\u00fcchtlingslager der Pal\u00e4stinenser: <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=2248\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=2248<\/font><\/a><\/strong> <\/p>\n<p>Die humane Kriegsf\u00fchrung von Israel mit v\u00f6llig unnat\u00fcrlichen Handlungen einer Armee im Gazastreifen: <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=2485\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=2485<\/font><\/a><\/strong><\/p>\n<p>Bei dem Tunnelbau der Hamas in Gaza f\u00fcr Massenmorde an Israelis starben 160 Kinder, die an den Tunneln gruben: <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=2485\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=2485<\/font><\/a><\/strong> <\/p>\n<p>Israel ist Opfer und nicht T\u00e4ter im Krieg gegen die Hamas in Gaza. EU &#038; Deutschland bezahlen den Krieg: <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=2480\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=2480<\/font><\/a><\/strong> <\/p>\n<p>Krieg zwischen der Hamas und Israel. Gazastreifen Bewohner nicht unschuldige Opfer! <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=2453\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=2453<\/font><\/a><\/strong> <\/p>\n<p>Raketenangriffe der Hamas aus dem Gazastreifen gegen Israel. Gegen verf\u00e4lschte Darstellung in den deutschen Medien. <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=1636\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=1636<\/font><\/a><\/strong><\/p>\n<p>Bibel, AT, Psalm 122,6-9: W\u00fcnschet Jerusalem Gl\u00fcck! Es m\u00f6ge wohlgehen denen, die dich lieben! <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=972\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=972<\/font><\/a><\/strong> <\/p>\n<p>EU verursacht politisches Erdbeben in Israel! Ein verbindliches Dekret der EU verbietet Zusammenarbeit! <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/?p=2263\"><font color=\"#000080\">https:\/\/ichthys-consulting.de\/blog\/?p=2263<\/font><\/a><\/strong><\/p>\n<p>Kirchen USA: \u201eUS-Gelder f\u00f6rdern Nahostkonflikt\u201c Hilfen m\u00fcssten eingestellt werden. Aber Israel ist GOTTES Volk! Wie europ\u00e4ische und amerikanische Steuergelder an pal\u00e4stinensische Terroristen flie\u00dfen! <strong><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=1834\"><font color=\"#000080\">https:\/\/rettung-fuer-deutschland.de\/blog\/?p=1834<\/font><\/a><\/strong><\/p>\n<p><a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2817\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ichthys-consulting.de\/foto-wp-israel-ist-das-licht-in-dieser-welt-620x731.jpg\" width=\"620\" height=\"731\" class=\"alignnone size-medium\" \/><\/a><\/p>\n<p><strong>Mehr \u00fcber den Autor lesen Sie im Buch\/eBook mit dem Titel: <a href=\"https:\/\/www.50-erfolgsgrundlagen.de\/\"><font color=\"#000080\">&#8222;50 biblische Erfolgsgrundlagen im Gesch\u00e4ftsleben&#8220;<\/font><\/a>, erschienen im <a href=\"https:\/\/www.epubli.de\/shop\/autor\/Uwe-Melzer\/2518\"><font color=\"#000080\">epubli-Verlag unter Buch-ISBN: 978-3-8442-2969-1 und eBook\/ePUB-ISBN: 978-3-8442-0365-3.<\/font><\/a><\/strong><\/p>\n<p><a href=\"https:\/\/www.rettung-fuer-deutschland.de\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/Grafik-WP-Deutschlandflagge-am-Mast-RfD-Logo-B280-H140.jpg\" alt=\"\" width=\"280\" height=\"140\" class=\"alignleft\" \/><\/a><strong><a title=\"Rettung &#038; Vision f\u00fcr Deutschland\" href=\"https:\/\/www.rettung-fuer-deutschland.de\"><font color=\"#000080\">Rettung &#038; Vision f\u00fcr Deutschland<\/font><\/a><\/strong><br \/>E-Mail: <a href=\"mailto:rfd@rettung-fuer-deutschland.de\"><font color=\"#000080\">rfd@rettung-fuer-deutschland.de<\/font><\/a><br \/>Internet: <a href=\"https:\/\/www.rettung-fuer-deutschland.de\/\"><font color=\"#000080\">www.rettung-fuer-deutschland.de<\/font><\/a><\/p>\n<p><a href=\"https:\/\/twitter.com\/share\" class=\"twitter-share-button\" data-url=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\" data-text=\"Der Inhalt der #Antisemitismus #DOKU #JUDEN #HASS, den #ARTE &#038; #WDR nicht zeigen wollen:\" data-lang=\"de\">Twittern<\/a><script>!function(d,s,id){var js,fjs=d.getElementsByTagName(s)[0];if(!d.getElementById(id)){js=d.createElement(s);js.id=id;js.src=\"\/\/platform.twitter.com\/widgets.js\";fjs.parentNode.insertBefore(js,fjs);}}(document,\"script\",\"twitter-wjs\");<\/script> <script type=\"text\/javascript\" src=\"https:\/\/apis.google.com\/js\/plusone.js\"> {lang: 'de'} <\/script><g:plusone><\/g:plusone><\/p>\n<div id=\"fb-root\"><\/div>\n<p><script src=\"https:\/\/connect.facebook.net\/de_DE\/all.js#appId=1849770545241294&amp;xfbml=1\"><\/script><fb:like href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842\" send=\"true\" width=\"450\" show_faces=\"true\" font=\"arial\"><\/fb:like><\/p>\n","protected":false},"excerpt":{"rendered":"<p>JUDEN-HASS &#8211; die Doku, die ARTE &#038; WDR nicht zeigen wollen! Die TV-Dokumentation belegt in Europa grassierenden, teils hoff\u00e4higen Judenhass, f\u00fcr den es nur zwei Worte gibt: ekelhaft und besch\u00e4mend. Seit Wochen wird bis in die h\u00f6chsten Ebenen der Politik \u00fcber diese \u2013 von Geb\u00fchrengeldern produzierte \u2013 Dokumentation diskutiert. Ohne dass die B\u00fcrger sie sehen d\u00fcrfen. Ohne dass sie sich ein Urteil bilden k\u00f6nnen. Der Verdacht liegt bitter nah, dass diese Dokumentation nicht gezeigt wird, weil sie politisch nicht genehm ist, weil sie ein antisemitisches Weltbild in weiten Teilen der Gesellschaft belegt, das ersch\u00fctternd ist. Deutschland ist ganz sicher nicht das Land, in dem antisemitische Vorurteile besch\u00f6nigt, verschwiegen, \u00fcbert\u00fcncht werden sollten. Unsere historische Verantwortung verpflichtet uns, den Uns\u00e4glichkeiten entschlossen entgegenzutreten, die diese Dokumentation belegt. Dazu m\u00fcssen alle wissen, womit wir es zu tun haben. Deswegen zeigte BILD f\u00fcr 24 Stunden online am 13.06.2017, redaktionell eingeordnet und eingebettet, was im TV nicht gezeigt werden sollte. Diese Dokumentation \u201eAuserw\u00e4hlt und ausgegrenzt Der Hass auf Juden in Europa\u201c wurde im Internet zensiert. Zwei Video-Links bei Youtube mussten wegen Zensur (bzw. Rechteverletzung) vom Netz genommen werden. Deshalb finden Sie hier die wichtigsten Inhalte der TV-Dokumentation: https:\/\/rettung-fuer-deutschland.de\/blog\/?p=2842<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,19,4,1718,3,246],"tags":[3011,1269,2976,2981,2980,3017,1937,2977,352,3008,2544,828,811,3004,2983,1866,832,1933,3006,2982],"class_list":["post-2842","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-deutschland","category-gesellschaft","category-islam","category-politik","category-religion","tag-anti-israel-demo","tag-antisemitismus","tag-antisemitismus-doku","tag-arte","tag-bds","tag-boykott","tag-deutschland","tag-dokumentation","tag-europa","tag-europaparlament","tag-hass","tag-israel","tag-juden","tag-juden-hass","tag-judenhass","tag-palaestina","tag-palastinenser","tag-politik","tag-tv-dokumentation","tag-wdr"],"_links":{"self":[{"href":"https:\/\/rettung-fuer-deutschland.de\/blog\/wp-json\/wp\/v2\/posts\/2842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rettung-fuer-deutschland.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rettung-fuer-deutschland.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rettung-fuer-deutschland.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rettung-fuer-deutschland.de\/blog\/wp-json\/wp\/v2\/comments?post=2842"}],"version-history":[{"count":0,"href":"https:\/\/rettung-fuer-deutschland.de\/blog\/wp-json\/wp\/v2\/posts\/2842\/revisions"}],"wp:attachment":[{"href":"https:\/\/rettung-fuer-deutschland.de\/blog\/wp-json\/wp\/v2\/media?parent=2842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rettung-fuer-deutschland.de\/blog\/wp-json\/wp\/v2\/categories?post=2842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rettung-fuer-deutschland.de\/blog\/wp-json\/wp\/v2\/tags?post=2842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}